{"id":147,"count":7,"description":"","link":"https:\/\/www.legolfclub.com\/en\/tag\/vaudreuil\/","name":"vaudreuil","slug":"vaudreuil","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>vaudreuil Archives - Le Golf Club<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.legolfclub.com\/en\/tag\/vaudreuil\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"vaudreuil Archives - Le Golf Club\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.legolfclub.com\/en\/tag\/vaudreuil\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Golf Club\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.legolfclub.com\/wp-content\/uploads\/2013\/10\/golfin-dorion-og-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.legolfclub.com\\\/en\\\/tag\\\/vaudreuil\\\/\",\"url\":\"https:\\\/\\\/www.legolfclub.com\\\/en\\\/tag\\\/vaudreuil\\\/\",\"name\":\"vaudreuil Archives - Le Golf Club\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.legolfclub.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.legolfclub.com\\\/en\\\/tag\\\/vaudreuil\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.legolfclub.com\\\/en\\\/tag\\\/vaudreuil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.legolfclub.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"vaudreuil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.legolfclub.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.legolfclub.com\\\/en\\\/\",\"name\":\"Le Golf Club\",\"description\":\"Golf int\u00e9rieur sur simulateur\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.legolfclub.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.legolfclub.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.legolfclub.com\\\/en\\\/#organization\",\"name\":\"Le Golf Club\",\"url\":\"https:\\\/\\\/www.legolfclub.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.legolfclub.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.legolfclub.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/www.legolfclub.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-retina.png\",\"width\":340,\"height\":43,\"caption\":\"Le Golf Club\"},\"image\":{\"@id\":\"https:\\\/\\\/www.legolfclub.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/legolfclub\\\/\",\"https:\\\/\\\/www.instagram.com\\\/legolfclub1\\\/?hl=en\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/MDLevac\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"vaudreuil Archives - Le Golf Club","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.legolfclub.com\/en\/tag\/vaudreuil\/","og_locale":"en_US","og_type":"article","og_title":"vaudreuil Archives - Le Golf Club","og_url":"https:\/\/www.legolfclub.com\/en\/tag\/vaudreuil\/","og_site_name":"Le Golf Club","og_image":[{"width":300,"height":300,"url":"https:\/\/www.legolfclub.com\/wp-content\/uploads\/2013\/10\/golfin-dorion-og-logo.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.legolfclub.com\/en\/tag\/vaudreuil\/","url":"https:\/\/www.legolfclub.com\/en\/tag\/vaudreuil\/","name":"vaudreuil Archives - Le Golf Club","isPartOf":{"@id":"https:\/\/www.legolfclub.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.legolfclub.com\/en\/tag\/vaudreuil\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.legolfclub.com\/en\/tag\/vaudreuil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.legolfclub.com\/en\/"},{"@type":"ListItem","position":2,"name":"vaudreuil"}]},{"@type":"WebSite","@id":"https:\/\/www.legolfclub.com\/en\/#website","url":"https:\/\/www.legolfclub.com\/en\/","name":"Le Golf Club","description":"Golf int\u00e9rieur sur simulateur","publisher":{"@id":"https:\/\/www.legolfclub.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.legolfclub.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.legolfclub.com\/en\/#organization","name":"Le Golf Club","url":"https:\/\/www.legolfclub.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.legolfclub.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.legolfclub.com\/wp-content\/uploads\/2021\/01\/logo-retina.png","contentUrl":"https:\/\/www.legolfclub.com\/wp-content\/uploads\/2021\/01\/logo-retina.png","width":340,"height":43,"caption":"Le Golf Club"},"image":{"@id":"https:\/\/www.legolfclub.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/legolfclub\/","https:\/\/www.instagram.com\/legolfclub1\/?hl=en","https:\/\/www.youtube.com\/user\/MDLevac"]}]}},"_links":{"self":[{"href":"https:\/\/www.legolfclub.com\/en\/wp-json\/wp\/v2\/tags\/147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legolfclub.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.legolfclub.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.legolfclub.com\/en\/wp-json\/wp\/v2\/posts?tags=147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}